{"id":82981,"date":"2026-09-01T20:28:41","date_gmt":"2026-09-01T18:28:41","guid":{"rendered":"https:\/\/www.modelcars24.de\/?post_type=product&#038;p=82981"},"modified":"2026-09-02T09:03:40","modified_gmt":"2026-09-02T07:03:40","slug":"bbr-ferrari-288-gto-medium-green-118","status":"publish","type":"product","link":"https:\/\/www.modelcars24.de\/ar\/bbr-ferrari-288-gto-medium-green-118\/","title":{"rendered":"BBR Ferrari 288 GTO &#8211; Medium Green | 1:18"},"content":{"rendered":"<h2>BBR Ferrari 288 GTO &#8211; Medium Green | 1:18<\/h2>\n<div class=\"product-intro\">\n<p>Der 1984 vorgestellte Sportwagen ging als erstes Modell des Herstellers mit einem V8-Turbomotor in die Automobilgeschichte ein. Bis 1987 entstanden lediglich 272 Exemplare dieses au\u00dfergew\u00f6hnlichen Fahrzeugs.<\/p>\n<p>Das von Leonardo Fioravanti bei Pininfarina entworfene Karosseriedesign zeichnet sich durch markante, muskul\u00f6se Radh\u00e4user sowie seitliche NACA-Lufteinl\u00e4sse aus. Drei pr\u00e4gnante Luftschlitze an den hinteren Kotfl\u00fcgeln dienen als direkte Hommage an den historischen 250 GTO mit 12-Zylinder-Motor.<\/p>\n<p>Angetrieben wird das Fahrzeug von einem l\u00e4ngs eingebauten, mittig platzierten 2,8-Liter-V8-Biturbomotor, der 400 PS leistet und eine Rekord-H\u00f6chstgeschwindigkeit von 304 km\/h erm\u00f6glicht. Zu den bedeutendsten mechanischen Innovationen z\u00e4hlte die spezielle Motoranordnung zur Unterbringung der beiden Turbolader sowie der gro\u00dffl\u00e4chige Einsatz von leichten und stabilen Werkstoffen wie Kevlar und Kohlefaser.<\/p>\n<p>Urspr\u00fcnglich f\u00fcr die FIA-Homologation der Gruppe B konzipiert, kam das Fahrzeug aufgrund der pl\u00f6tzlichen Einstellung dieser Rennklasse nie im regul\u00e4ren Motorsport zum Einsatz. Dennoch bildete die Konstruktion die technische Grundlage f\u00fcr den 650 PS starken Prototypen GTO Evoluzione, aus dem sp\u00e4ter der F40 hervorging.<\/p>\n<p><strong>\u0645\u0644\u0627\u062d\u0638\u0629:<\/strong> Dieses Modell wird inklusive einer hochwertigen Pr\u00e4sentationsvitrine geliefert.<\/p>\n<\/div>\n<p>\n<strong>\u062d\u0627\u0644\u0629<\/strong> \u062c\u062f\u064a\u062f \u062a\u0645\u0627\u0645\u064b\u0627<br \/>\n<strong>\u0631\u0642\u0645 \u0627\u0644\u0642\u0637\u0639\u0629 (SKU):<\/strong> P18288F<\/p>","protected":false},"excerpt":{"rendered":"<p>BBR Ferrari 288 GTO &#8211; P18288F \u2013 preorder \u2013 426 inkl. 19% Vat<\/p>","protected":false},"featured_media":82980,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[262],"product_tag":[],"class_list":["post-82981","product","type-product","status-publish","has-post-thumbnail","product_cat-vorbestellbar","pa_automarke-ferrari","pa_decade-1980s","pa_fahrzeugtyp-supersportwagen","pa_farbe-verde-medio","pa_limitiert-ja","pa_massstab-973","pa_modelmarke-bbr","pa_modeltyp-geschlossenfertigmodell","pa_verfuegbarkeit-vorbestellbar","pa_zustand_modell-1-brandneu","pa_zustand_verpackung-1-brandneu","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.modelcars24.de\/ar\/wp-json\/wp\/v2\/product\/82981","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.modelcars24.de\/ar\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.modelcars24.de\/ar\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.modelcars24.de\/ar\/wp-json\/wp\/v2\/comments?post=82981"}],"version-history":[{"count":1,"href":"https:\/\/www.modelcars24.de\/ar\/wp-json\/wp\/v2\/product\/82981\/revisions"}],"predecessor-version":[{"id":83022,"href":"https:\/\/www.modelcars24.de\/ar\/wp-json\/wp\/v2\/product\/82981\/revisions\/83022"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.modelcars24.de\/ar\/wp-json\/wp\/v2\/media\/82980"}],"wp:attachment":[{"href":"https:\/\/www.modelcars24.de\/ar\/wp-json\/wp\/v2\/media?parent=82981"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.modelcars24.de\/ar\/wp-json\/wp\/v2\/product_brand?post=82981"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.modelcars24.de\/ar\/wp-json\/wp\/v2\/product_cat?post=82981"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.modelcars24.de\/ar\/wp-json\/wp\/v2\/product_tag?post=82981"}],"curies":[{"name":"\u062f\u0628\u0644\u064a\u0648 \u0628\u064a","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}