{"id":34482,"date":"2025-12-05T00:00:00","date_gmt":"2025-12-04T23:00:00","guid":{"rendered":"http:\/\/www.mondo-legno.com\/?post_type=product&#038;p=34482"},"modified":"2026-04-24T11:39:38","modified_gmt":"2026-04-24T09:39:38","slug":"amalgama-amalgama-ferrari-dino-246-gt-1972","status":"publish","type":"product","link":"https:\/\/www.modelcars24.de\/es\/amalgam-amalgam-ferrari-dino-246-gt-1972\/","title":{"rendered":"Amalgama Ferrari Dino 246 GT (1969) | Euro Edition - 1\/8"},"content":{"rendered":"<p>Amalgama Ferrari Dino 246 GT (1969) | Euro Edition<\/p>\n<p>El Dino 246 GT est\u00e1 considerado uno de los Ferrari de calle m\u00e1s bellos de todos los tiempos y fue el sucesor m\u00e1s potente del 206 GT. Era una delicia desde todos los \u00e1ngulos y su combinaci\u00f3n de belleza, maniobrabilidad, sonido del motor V6, disposici\u00f3n del motor en posici\u00f3n central, visibilidad panor\u00e1mica inusualmente buena y precio comparativamente favorable lo hac\u00edan irresistible. Enzo concibi\u00f3 el Dino como rival del nuevo 911 de Porsche y supuso una aut\u00e9ntica declaraci\u00f3n de concepto y dise\u00f1o para la marca italiana, que hasta entonces s\u00f3lo hab\u00eda fabricado deportivos V12 con motor delantero.<\/p>\n<p>El Dino 206 GT original se present\u00f3 en 1967 con un motor V6 de dos litros, antes de ser sustituido en 1969 por una versi\u00f3n m\u00e1s potente con un V6 de 2,4 litros en el Dino 246. Con 195 CV, el 246 era vivaz y ten\u00eda un motor central en la parte trasera. La configuraci\u00f3n aseguraba una direcci\u00f3n ligera y un equilibrio excelente. Visualmente, el 246 GT era casi id\u00e9ntico a su sucesor, el 206 GT, aunque el material del bloque motor se cambi\u00f3 de aluminio a hierro fundido y la distancia entre ejes se ampli\u00f3 60 mm. Con la venta del Dino 246 GT en 1972, Ferrari intent\u00f3 aumentar a\u00fan m\u00e1s su popularidad introduciendo una versi\u00f3n descapotable. El dise\u00f1o conservaba las l\u00edneas individuales y atractivas del 264 GT, con la ventaja a\u00f1adida de una pr\u00e1ctica capota targa para conducir al aire libre.<br \/>\nN\u00famero de art\u00edculo: M5751-ERO<\/p>","protected":false},"excerpt":{"rendered":"<p>1:8 &#8211; 1-brandneu &#8211; anstatt 21995,00 \u20ac jetzt 15400,00 \u20ac inkl. 19% Vat<\/p>","protected":false},"featured_media":34483,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[864],"product_cat":[286,63,21],"product_tag":[288,209,202],"class_list":["post-34482","product","type-product","status-publish","has-post-thumbnail","product_brand-amalgam","product_cat-amalgam","product_cat-ferrari","product_cat-verfuegbar","product_tag-amalgam","product_tag-ferrari","product_tag-verfuegbar","pa_automarke-ferrari","pa_decade-1970s","pa_fahrzeugtyp-coupe","pa_massstab-1-8","pa_modelmarke-amalgam","pa_modeltyp-alles-zum-oeffnen","pa_modeltyp-fertigmodell","pa_status-beim-hersteller-verfuegbar","pa_verfuegbarkeit-5-tage-lieferzeit","pa_zustand_modell-1-brandneu","pa_zustand_verpackung-1-brandneu","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.modelcars24.de\/es\/wp-json\/wp\/v2\/product\/34482","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.modelcars24.de\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.modelcars24.de\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.modelcars24.de\/es\/wp-json\/wp\/v2\/comments?post=34482"}],"version-history":[{"count":0,"href":"https:\/\/www.modelcars24.de\/es\/wp-json\/wp\/v2\/product\/34482\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.modelcars24.de\/es\/wp-json\/wp\/v2\/media\/34483"}],"wp:attachment":[{"href":"https:\/\/www.modelcars24.de\/es\/wp-json\/wp\/v2\/media?parent=34482"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.modelcars24.de\/es\/wp-json\/wp\/v2\/product_brand?post=34482"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.modelcars24.de\/es\/wp-json\/wp\/v2\/product_cat?post=34482"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.modelcars24.de\/es\/wp-json\/wp\/v2\/product_tag?post=34482"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}