{"id":52364,"date":"2025-07-02T10:46:01","date_gmt":"2025-07-02T08:46:01","guid":{"rendered":"https:\/\/www.modelcars24.de\/?post_type=product&#038;p=52364"},"modified":"2025-12-10T13:38:43","modified_gmt":"2025-12-10T12:38:43","slug":"bbr-ferrari-f355-berlinetta-1994-cambio-manual-giallo-modena","status":"publish","type":"product","link":"https:\/\/www.modelcars24.de\/es\/bbr-ferrari-f355-berlinetta-1994-manual-gear-giallo-modena\/","title":{"rendered":"BBR Ferrari F355 Berlinetta 1994 cambio manual Giallo Modena - interior negro - 1\/18"},"content":{"rendered":"<h2>BBR Ferrari F355 Berlinetta 1994 cambio manual <span class=\"BBR_SchedaProdotto_SubTitle\">Giallo Modena - interior negro<\/span>.<\/h2>\n<p>El Ferrari F355 es un autom\u00f3vil deportivo biplaza con un motor central de 8 cilindros en la parte trasera, que fue producido por el fabricante de autom\u00f3viles italiano Ferrari de 1994 a 1999.<br \/>\nEl nombre 355 de este modelo hace referencia a una cilindrada de 3,5 litros y cinco v\u00e1lvulas por cilindro. Durante la fase de dise\u00f1o, Ferrari empez\u00f3 a trasladar algunos de los descubrimientos del mundo de la F\u00f3rmula 1 a los coches de producci\u00f3n: inyecci\u00f3n electr\u00f3nica de combustible, suelo plano, caja de cambios secuencial y suspensi\u00f3n controlada electr\u00f3nicamente, que puede ajustarse en dos posiciones diferentes desde el puesto de conducci\u00f3n: Normal y Sport. Esta \u00faltima endurec\u00eda especialmente el chasis y aceleraba los cambios de marcha en las versiones con caja de cambios secuencial controlada el\u00e9ctricamente.<br \/>\nEl F355 tambi\u00e9n fue innovador gracias a un exhaustivo estudio aerodin\u00e1mico realizado por Pininfarina, tanto en lo que respecta a las condiciones de flujo en los bajos totalmente panelados del veh\u00edculo como alrededor del habit\u00e1culo.<\/p>\n<p>N\u00famero de art\u00edculo: P18140B<\/p>\n<p>con cap\u00f3 acr\u00edlico<\/p>","protected":false},"excerpt":{"rendered":"<p>P18140B &#8211; preorder &#8211; anstatt 458,00 jetzt 395,00 \u20ac inkl. 19% Vat<\/p>","protected":false},"featured_media":52354,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[851],"product_cat":[169,63,262],"product_tag":[173,209,263],"class_list":["post-52364","product","type-product","status-publish","has-post-thumbnail","product_brand-bbr","product_cat-bbr","product_cat-ferrari","product_cat-vorbestellbar","product_tag-bbr","product_tag-ferrari","product_tag-vorbestellbar","pa_automarke-ferrari","pa_decade-2000s","pa_fahrzeugtyp-coupe","pa_massstab-1-18","pa_modelmarke-bbr","pa_modeltyp-fertigmodell","pa_modeltyp-geschlossen","pa_status-beim-hersteller-verfuegbar","pa_verfuegbarkeit-vorbestellbar","pa_zustand_modell-1-brandneu","pa_zustand_verpackung-1-brandneu","first","instock","sale","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.modelcars24.de\/es\/wp-json\/wp\/v2\/product\/52364","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.modelcars24.de\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.modelcars24.de\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.modelcars24.de\/es\/wp-json\/wp\/v2\/comments?post=52364"}],"version-history":[{"count":0,"href":"https:\/\/www.modelcars24.de\/es\/wp-json\/wp\/v2\/product\/52364\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.modelcars24.de\/es\/wp-json\/wp\/v2\/media\/52354"}],"wp:attachment":[{"href":"https:\/\/www.modelcars24.de\/es\/wp-json\/wp\/v2\/media?parent=52364"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.modelcars24.de\/es\/wp-json\/wp\/v2\/product_brand?post=52364"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.modelcars24.de\/es\/wp-json\/wp\/v2\/product_cat?post=52364"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.modelcars24.de\/es\/wp-json\/wp\/v2\/product_tag?post=52364"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}