{"id":71132,"date":"2026-07-15T13:16:05","date_gmt":"2026-07-15T11:16:05","guid":{"rendered":"https:\/\/www.modelcars24.de\/?post_type=product&#038;p=71132"},"modified":"2026-07-15T16:35:47","modified_gmt":"2026-07-15T14:35:47","slug":"autoart-lamborghini-diablo-gtr-1999-118-ishtar-orange","status":"publish","type":"product","link":"https:\/\/www.modelcars24.de\/es\/autoart-lamborghini-diablo-gtr-1999-118-ishtar-orange\/","title":{"rendered":"AUTOart Lamborghini Diablo GTR 1999 1:18 \u2013 Naranja Ishtar"},"content":{"rendered":"<h2>AUTOart Lamborghini Diablo GTR 1999 1:18 \u2013 Naranja Ishtar<\/h2>\n<div class=\"product-intro\">\n<p>Der 1999 pr\u00e4sentierte Lamborghini Diablo GTR wurde als kompromisslose, rennstreckenorientierte Evolution des Diablo GT konzipiert. Mit einer Karosserie, die zur signifikanten Gewichtsreduktion weitgehend aus Kohlefaser gefertigt wurde, und einem auf rund 590 PS modifizierten 6,0-Liter-V12-Saugmotor, war das Fahrzeug exklusiv f\u00fcr den Lamborghini Supertrofeo-Markenpokal vorgesehen. Aerodynamische Spezifikationen wie der markante, direkt mit dem Chassis verschraubte Heckfl\u00fcgel und die tief gezogene Frontsch\u00fcrze pr\u00e4gen das technische Gesamtkonzept dieser puristischen Fahrmaschine.<\/p>\n<p>Das Modell von AUTOart reflektiert die komplexe Ingenieurskunst des historischen Vorbilds mit hoher Pr\u00e4zision. Wie von der Manufaktur gewohnt, lassen sich die klassischen Scherent\u00fcren sowie die Hauben \u00f6ffnen und geben den Blick auf die tiefgreifende Mechanik frei. Der Heckbereich offenbart einen fein strukturierten Motorraum, in dem Leitungen, Abdeckungen und das Abgassystem ma\u00dfstabsgetreu nachgebildet sind. Auch der Innenraum besticht durch eine exakte Umsetzung der rennspezifischen Bedienelemente, Schalensitze und der Sicherheitsstruktur. Abgerundet wird die Authentizit\u00e4t dieses Modells durch voll lenkbare Vorderr\u00e4der und eine akkurate Lackierung im originalen Farbton.<\/p>\n<\/div>\n<p><strong>Zustand:<\/strong> 1 &#8211; brandneu<br \/>\n<strong>Artikelnummer (SKU):<\/strong>79139<\/p>","protected":false},"excerpt":{"rendered":"<p>AUTOart Lamborghini Diablo GTR &#8211; 79139 \u2013 1-brandneu \u2013 295\u20ac inkl. 19% Vat<\/p>","protected":false},"featured_media":71111,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[21],"product_tag":[],"class_list":["post-71132","product","type-product","status-publish","has-post-thumbnail","product_cat-verfuegbar","pa_automarke-lamborghini","pa_decade-1990er","pa_fahrzeugtyp-sportwagen","pa_farbe-ishtar-orange","pa_limitiert-nein","pa_massstab-973","pa_modelmarke-autoart","pa_modeltyp-alles-zum-oeffnen-fertigmodell","pa_verfuegbarkeit-verfuegbar","pa_zustand_modell-1-brandneu","pa_zustand_verpackung-1-brandneu","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.modelcars24.de\/es\/wp-json\/wp\/v2\/product\/71132","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.modelcars24.de\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.modelcars24.de\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.modelcars24.de\/es\/wp-json\/wp\/v2\/comments?post=71132"}],"version-history":[{"count":1,"href":"https:\/\/www.modelcars24.de\/es\/wp-json\/wp\/v2\/product\/71132\/revisions"}],"predecessor-version":[{"id":71763,"href":"https:\/\/www.modelcars24.de\/es\/wp-json\/wp\/v2\/product\/71132\/revisions\/71763"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.modelcars24.de\/es\/wp-json\/wp\/v2\/media\/71111"}],"wp:attachment":[{"href":"https:\/\/www.modelcars24.de\/es\/wp-json\/wp\/v2\/media?parent=71132"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.modelcars24.de\/es\/wp-json\/wp\/v2\/product_brand?post=71132"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.modelcars24.de\/es\/wp-json\/wp\/v2\/product_cat?post=71132"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.modelcars24.de\/es\/wp-json\/wp\/v2\/product_tag?post=71132"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}