{"id":225,"date":"2025-07-08T11:54:23","date_gmt":"2025-07-08T09:54:23","guid":{"rendered":"https:\/\/www.modelcars24.de\/?post_type=product&#038;p=225"},"modified":"2026-08-06T17:11:45","modified_gmt":"2026-08-06T15:11:45","slug":"cmc-bugatti-57-sc-corsica-version-primee","status":"publish","type":"product","link":"https:\/\/www.modelcars24.de\/fr\/cmc-bugatti-57-sc-corsica-award-winning-version\/","title":{"rendered":"CMC Bugatti 57 SC Corsica Award Winning Version - 1\/18"},"content":{"rendered":"<h3>CMC Bugatti 57 SC Corsica Award Winning Version<\/h3>\n<p>Pebble Beach Concours d'El\u00e9gance, Award Winning Version \u201eBest of Show.<br \/>\nLa plus extraordinaire, la plus exclusive et la plus belle des Bugatti avec int\u00e9rieur en imitation cuir crocodile.<\/p>\n<div>\n<ul>\n<li>Mod\u00e8le de pr\u00e9cision en m\u00e9tal assembl\u00e9 \u00e0 la main, compos\u00e9 d'environ 1780 pi\u00e8ces<\/li>\n<li>Peinture de haute qualit\u00e9 d'un brillant \u00e9clatant<\/li>\n<li>Carrosserie authentique et \u00e0 l'\u00e9chelle du v\u00e9hicule actuel (John Mozart) aux lignes \u00e9l\u00e9gantes<\/li>\n<li>Repr\u00e9sentation fid\u00e8le de la partie avant du v\u00e9hicule avec les phares int\u00e9gr\u00e9s de mani\u00e8re esth\u00e9tique<\/li>\n<li>Roues \u00e0 rayons parfaites et fermetures centrales vissables \u00e0 deux ailes avec filetage \u00e0 droite\/gauche pour le d\u00e9montage des roues<\/li>\n<li>Tableau de bord finement \u00e9labor\u00e9 avec tous les instruments d'affichage et les boutons de commande<\/li>\n<li>Moteur 8 cylindres en ligne hautement d\u00e9taill\u00e9 avec tous les \u00e9l\u00e9ments rapport\u00e9s et pose compl\u00e8te des conduites et du c\u00e2blage<\/li>\n<li>Ensemble de sol \u00e9labor\u00e9 avec repr\u00e9sentation du syst\u00e8me d'\u00e9chappement en acier inoxydable<\/li>\n<li>Ch\u00e2ssis du v\u00e9hicule con\u00e7u avec pr\u00e9cision comme une construction m\u00e9tallique<\/li>\n<li>Capot moteur \u00e0 double battant ouvrable avec possibilit\u00e9 de rangement sur des broches m\u00e9talliques sp\u00e9cialement pr\u00e9vues \u00e0 cet effet<\/li>\n<li>Portes conducteur et passager mobiles articul\u00e9es sur des charni\u00e8res finement model\u00e9es<\/li>\n<li>Le coffre verrouillable contient un cric, une pompe \u00e0 air, une pompe \u00e0 graisse, des bo\u00eetes de pi\u00e8ces et un kit d'outils miniatures.<\/li>\n<\/ul>\n<\/div>\n<div>Description du v\u00e9hicule original:Le colonel Godfrey Giles, un Anglais, a achet\u00e9 en 1937 un ch\u00e2ssis de Bugatti 57 S pour y faire carrosser un roadster. Son fr\u00e8re, Eric Giles, s'est charg\u00e9 du d\u00e9veloppement du design de la carrosserie et le carrossier anglais Corsica a r\u00e9alis\u00e9 la carrosserie sur la base de ces plans. Il en r\u00e9sulta un roadster d'une beaut\u00e9 envo\u00fbtante qui fut immatricul\u00e9 en 1938 sous le num\u00e9ro GU7.<br \/>\nEn raison de probl\u00e8mes de moteur ult\u00e9rieurs, un compresseur et des pistons modifi\u00e9s ont \u00e9t\u00e9 ajout\u00e9s pour rem\u00e9dier \u00e0 la situation. C'est ainsi qu'est n\u00e9e la nouvelle d\u00e9signation 57 SC (C = compresseur).<br \/>\nEn 1985, le v\u00e9hicule est devenu la propri\u00e9t\u00e9 de John Mozart, c\u00e9l\u00e8bre collectionneur de voitures anciennes en Californie. Fin 1995, John Mozart a entrepris une restauration compl\u00e8te du v\u00e9hicule. Au final, la collection de Mozart comportait un roadster bleu fonc\u00e9 magnifiquement restaur\u00e9, qui a remport\u00e9 le titre convoit\u00e9 de \u201eBest of Show\u201c au concours de Pebble Beach en 1998.<br \/>\nCMC a reproduit le v\u00e9hicule de Mozart dans sa splendeur actuelle, avec son design de cockpit frappant, en \u00e9dition limit\u00e9e \u00e0 1000 exemplaires dans le monde entier.<br \/>\nCMC remercie Monsieur Mozart et la soci\u00e9t\u00e9 Bugatti S.A.S - Tradition pour leur aimable soutien.<\/div>\n<p>Num\u00e9ro d'article : M-136<\/p>","protected":false},"excerpt":{"rendered":"<p>M-136 &#8211; 2-neuwertig &#8211; 650,00 \u20ac<\/p>","protected":false},"featured_media":40886,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[537],"product_cat":[77,18,45,21],"product_tag":[226],"class_list":["post-225","product","type-product","status-publish","has-post-thumbnail","product_brand-cmc","product_cat-bugatti","product_cat-cmc","product_cat-neuzugang","product_cat-verfuegbar","product_tag-cmc-bugatti-57-sc-corsica","pa_automarke-bugatti","pa_decade-1930s","pa_fahrzeugtyp-cabrio","pa_farbe-blau","pa_limitiert-ja","pa_massstab-973","pa_modelmarke-cmc","pa_modeltyp-alles-zum-oeffnen","pa_modeltyp-fertigmodell","pa_status-beim-hersteller-ausverkauft","pa_verfuegbarkeit-nicht-verfuegbar","pa_zustand_modell-2-neuwertig","pa_zustand_verpackung-2-neuwertig","first","outofstock","purchasable","product-type-simple"],"acf":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.modelcars24.de\/fr\/wp-json\/wp\/v2\/product\/225","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.modelcars24.de\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.modelcars24.de\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.modelcars24.de\/fr\/wp-json\/wp\/v2\/comments?post=225"}],"version-history":[{"count":0,"href":"https:\/\/www.modelcars24.de\/fr\/wp-json\/wp\/v2\/product\/225\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.modelcars24.de\/fr\/wp-json\/wp\/v2\/media\/40886"}],"wp:attachment":[{"href":"https:\/\/www.modelcars24.de\/fr\/wp-json\/wp\/v2\/media?parent=225"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.modelcars24.de\/fr\/wp-json\/wp\/v2\/product_brand?post=225"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.modelcars24.de\/fr\/wp-json\/wp\/v2\/product_cat?post=225"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.modelcars24.de\/fr\/wp-json\/wp\/v2\/product_tag?post=225"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}