{"id":61423,"date":"2026-02-24T11:44:40","date_gmt":"2026-02-24T10:44:40","guid":{"rendered":"https:\/\/www.modelcars24.de\/?post_type=product&#038;p=61423"},"modified":"2026-02-25T12:26:13","modified_gmt":"2026-02-25T11:26:13","slug":"bbr-ferrari-enzo-open-diecast-rosso-corsa-black-and-red-wheels-polifoam-pack-1-18","status":"publish","type":"product","link":"https:\/\/www.modelcars24.de\/fr\/bbr-ferrari-enzo-open-diecast-rosso-corsa-black-and-red-wheels-polifoam-pack-1-18\/","title":{"rendered":"BBR Ferrari Enzo open diecast Rosso Corsa - Black and red wheels - polifoam pack - 1\/18"},"content":{"rendered":"<h2>BBR Ferrari Enzo open diecast Rosso Corsa - Black and red wheels - polifoam pack - 1\/18<\/h2>\n<p>BBR pr\u00e9sente un nouveau mod\u00e8le. Gr\u00e2ce \u00e0 une technologie moderne, les portes ont \u00e9t\u00e9 redessin\u00e9es et s'ouvrent de mani\u00e8re plus r\u00e9aliste. Outre les \u00e9conomies r\u00e9alis\u00e9es gr\u00e2ce aux nouvelles formes, l'int\u00e9rieur a \u00e9t\u00e9 am\u00e9lior\u00e9 avec des si\u00e8ges soft touch et des ceintures en tissu. Le ch\u00e2ssis est enti\u00e8rement fonctionnel et dispose d'un aileron arri\u00e8re mobile. Les portes, le capot et le bouchon de r\u00e9servoir s'ouvrent.<\/p>\n<p>Ce mod\u00e8le se distingue par ses d\u00e9tails r\u00e9alistes, comme les valises qui se rangent dans le coffre et la possibilit\u00e9 d'enlever les roues \u00e0 l'aide d'une cl\u00e9 sp\u00e9ciale, \u00e0 l'\u00e9chelle. Il se compose de 570 pi\u00e8ces.<\/p>\n<p>L'hommage du cheval bondissant \u00e0 son fondateur. La Ferrari Enzo a \u00e9t\u00e9 pr\u00e9sent\u00e9e en 2002, une ann\u00e9e qui a marqu\u00e9 une \u00e9tape importante dans la carri\u00e8re triomphale de Michael Schumacher en Formule 1 : Apr\u00e8s seulement onze Grands Prix, l'Allemand a remport\u00e9 le championnat du monde des pilotes. Construite en 399 exemplaires, l'Enzo est n\u00e9e du transfert de technologie des voitures de course aux voitures de route. La carrosserie de Pininfarina allie style et fonctionnalit\u00e9 et se distingue par des lignes puissantes avec une partie avant inspir\u00e9e de la F2002 avec laquelle Schumacher a couru en Formule 1.<\/p>\n<p>Base et vitrine incluses<\/p>\n<p>Num\u00e9ro d'article : HE182501B<\/p>","protected":false},"excerpt":{"rendered":"<p>HE182501B &#8211;\u00a0 preorder &#8211; 355,00 \u20ac inkl. 19% vat<\/p>","protected":false},"featured_media":61424,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[851],"product_cat":[169,63,262],"product_tag":[173,209,202],"class_list":["post-61423","product","type-product","status-publish","has-post-thumbnail","product_brand-bbr","product_cat-bbr","product_cat-ferrari","product_cat-vorbestellbar","product_tag-bbr","product_tag-ferrari","product_tag-verfuegbar","pa_automarke-ferrari","pa_decade-2020s","pa_fahrzeugtyp-gt-rennen","pa_farbe-rot","pa_limitiert-ja","pa_massstab-1-18","pa_modelmarke-bbr","pa_modeltyp-fertigmodell","pa_modeltyp-geschlossen","pa_status-beim-hersteller-verfuegbar","pa_verfuegbarkeit-vorbestellbar","pa_zustand_modell-1-brandneu","pa_zustand_verpackung-1-brandneu","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.modelcars24.de\/fr\/wp-json\/wp\/v2\/product\/61423","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.modelcars24.de\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.modelcars24.de\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.modelcars24.de\/fr\/wp-json\/wp\/v2\/comments?post=61423"}],"version-history":[{"count":0,"href":"https:\/\/www.modelcars24.de\/fr\/wp-json\/wp\/v2\/product\/61423\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.modelcars24.de\/fr\/wp-json\/wp\/v2\/media\/61424"}],"wp:attachment":[{"href":"https:\/\/www.modelcars24.de\/fr\/wp-json\/wp\/v2\/media?parent=61423"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.modelcars24.de\/fr\/wp-json\/wp\/v2\/product_brand?post=61423"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.modelcars24.de\/fr\/wp-json\/wp\/v2\/product_cat?post=61423"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.modelcars24.de\/fr\/wp-json\/wp\/v2\/product_tag?post=61423"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}