{"id":69376,"date":"2026-07-14T14:04:20","date_gmt":"2026-07-14T12:04:20","guid":{"rendered":"https:\/\/www.modelcars24.de\/?post_type=product&#038;p=69376"},"modified":"2026-07-14T18:08:55","modified_gmt":"2026-07-14T16:08:55","slug":"autoart-ford-gt-2017-112-liquid-red-silver-stripes","status":"publish","type":"product","link":"https:\/\/www.modelcars24.de\/fr\/autoart-ford-gt-2017-112-liquid-red-silver-stripes\/","title":{"rendered":"AUTOart Ford GT 2017 1:12 \u2013 Rouge Liquide \/ Bandes Argent\u00e9es"},"content":{"rendered":"<h2>AUTOart Ford GT 2017 1:12 \u2013 Rouge Liquide \/ Bandes Argent\u00e9es<\/h2>\n<div class=\"product-intro\">\n<p>La Ford GT mill\u00e9sime 2017 repr\u00e9sente une synth\u00e8se fascinante entre l'h\u00e9ritage historique du sport automobile et une technologie automobile de pointe. D\u00e9velopp\u00e9e pour faire suite aux succ\u00e8s de la classique GT40, juste \u00e0 temps pour le 50e anniversaire de la l\u00e9gendaire victoire du Mans en 1966, cette voiture de sport haute performance s\u00e9duit par sa forme en goutte d'eau optimis\u00e9e sur le plan a\u00e9rodynamique et une construction innovante en fibre de carbone. Propuls\u00e9 par un moteur EcoBoost V6 de 3,5 litres, ce v\u00e9hicule original marque un sommet a\u00e9rodynamique et performant dans l'histoire r\u00e9cente de la marque Ford.<\/p>\n<p>AUTOart pr\u00e9sente le v\u00e9hicule comme un mod\u00e8le de pr\u00e9cision grand format \u00e0 l'\u00e9chelle imposante de 1:12. La carrosserie arbore une finition impeccable dans la teinte intensive Rouge Liquide, qui est compl\u00e9t\u00e9e visuellement par les bandes de course argent\u00e9es (Silver Stripes) caract\u00e9ristiques. Le fabricant opte ici pour une construction enti\u00e8rement mobile : les portes caract\u00e9ristiques s'ouvrent, tout comme le capot avant et le compartiment arri\u00e8re du moteur, qui est g\u00e9n\u00e9reux. Ce dernier dissimule une r\u00e9plique fid\u00e8le et d\u00e9taill\u00e9e du moteur biturbo, y compris tous les organes auxiliaires essentiels. L'aspect g\u00e9n\u00e9ral r\u00e9aliste est compl\u00e9t\u00e9 par des roues avant fonctionnelles et directionnelles ainsi qu'un habitacle authentiquement con\u00e7u, qui refl\u00e8te avec pr\u00e9cision l'architecture minimaliste et ax\u00e9e sur le conducteur du v\u00e9ritable GT.<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>AUTOart Ford GT &#8211; 12106 \u2013 1-brandneu \u2013 554 inkl. 19% Vat<\/p>","protected":false},"featured_media":69356,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[21],"product_tag":[],"class_list":["post-69376","product","type-product","status-publish","has-post-thumbnail","product_cat-verfuegbar","pa_automarke-ford","pa_decade-2010er","pa_fahrzeugtyp-sportwagen","pa_farbe-liquid-red","pa_limitiert-nein","pa_massstab-992","pa_modelmarke-autoart","pa_modeltyp-alles-zum-oeffnen-fertigmodell","pa_verfuegbarkeit-verfuegbar","pa_zustand_modell-1-brandneu","pa_zustand_verpackung-1-brandneu","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.modelcars24.de\/fr\/wp-json\/wp\/v2\/product\/69376","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.modelcars24.de\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.modelcars24.de\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.modelcars24.de\/fr\/wp-json\/wp\/v2\/comments?post=69376"}],"version-history":[{"count":1,"href":"https:\/\/www.modelcars24.de\/fr\/wp-json\/wp\/v2\/product\/69376\/revisions"}],"predecessor-version":[{"id":69556,"href":"https:\/\/www.modelcars24.de\/fr\/wp-json\/wp\/v2\/product\/69376\/revisions\/69556"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.modelcars24.de\/fr\/wp-json\/wp\/v2\/media\/69356"}],"wp:attachment":[{"href":"https:\/\/www.modelcars24.de\/fr\/wp-json\/wp\/v2\/media?parent=69376"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.modelcars24.de\/fr\/wp-json\/wp\/v2\/product_brand?post=69376"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.modelcars24.de\/fr\/wp-json\/wp\/v2\/product_cat?post=69376"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.modelcars24.de\/fr\/wp-json\/wp\/v2\/product_tag?post=69376"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}