{"id":134,"date":"2025-10-05T11:54:02","date_gmt":"2025-10-05T09:54:02","guid":{"rendered":"http:\/\/www.mondo-legno.com\/?post_type=product&#038;p=134"},"modified":"2026-08-11T10:37:44","modified_gmt":"2026-08-11T08:37:44","slug":"cmc-ferrari-156f1-1961-hill-monza-numero-di-partenza-2","status":"publish","type":"product","link":"https:\/\/www.modelcars24.de\/it\/cmc-ferrari-156f1-1961-hill-monza-startnummer-2\/","title":{"rendered":"CMC Ferrari 156F1, 1961, Hill \/ Monza, numero di partenza 2 - 1\/18"},"content":{"rendered":"<h3>CMC Ferrari 156F1, 1961, Hill \/ Monza, numero di partenza 2<\/h3>\n<div>\n<ul>\n<li>Modello di precisione in metallo assemblato a mano e composto da 1640 parti<\/li>\n<li>Corpo stampato autentico e fedele alla scala con verniciatura brillante<\/li>\n<li>Design prototipale della cabina di pilotaggio<\/li>\n<li>Scocca del sedile con rivestimento in tessuto e bordi in pelle<\/li>\n<li>Cruscotto completamente strumentato<\/li>\n<li>Sospensione a ruote indipendenti su quadrilateri metallici con molle elicoidali<\/li>\n<li>Ammortizzatori telescopici interni<\/li>\n<li>Sistema di scarico con gomiti per tubi metallici<\/li>\n<li>Collettori di aspirazione del carburatore in rete metallica fine (con cofani in plastica chiusi sul modello con numero di avviamento 3) e imbuti del carburatore in acciaio inox<\/li>\n<li>Autentico parabrezza in tre parti in vetro plastico di alta qualit\u00e0 (sul modello con numero di partenza 4 con deflettore allegato)<\/li>\n<li>Una caratteristica che colpisce dell'auto da corsa piatta e allungata \u00e8 il suo muso affusolato con le due grandi aperture per l'aria di raffreddamento a forma di narice. Da qui il soprannome \u201eSharknose\u201c (naso di squalo).<\/li>\n<li>Dinamica allo stato puro! La campanatura negativa delle ruote posteriori \u00e8 una caratteristica deliberata del design. Il gruppo frizione esterno \u00e8 visibile dietro la griglia posteriore.<\/li>\n<li>Riproduzione altamente dettagliata del motore a sei cilindri a V con cambio e frizione esterna<\/li>\n<li>Dischi freno posteriori interni con alberi di trasmissione<\/li>\n<li>Posa e cablaggio completi<\/li>\n<li>La sezione di prua pu\u00f2 essere rimossa allentando due viti.<\/li>\n<li>Serbatoio dell'olio e serbatoio del carburante ausiliario, nonch\u00e9 serbatoi laterali del carburante in acciaio inox verniciato<\/li>\n<li>Sportelli mobili della sezione di prua come accesso al bocchettone mobile dell'olio e alla presa d'aria per il sistema di raffreddamento del vano piedi del pozzetto<\/li>\n<li>Telaio tubolare a traliccio come struttura metallica in filigrana<\/li>\n<li>Roll bar in metallo cromato<\/li>\n<li>Tubi dei freni, del carburante e di sfiato<\/li>\n<li>Tubi per acqua e olio (lubrificazione a carter secco)<\/li>\n<li>Tracciamento autentico della batteria<\/li>\n<li>Ruote smontabili con cerchi in alluminio e raggi in filo d'acciaio inossidabile montati a mano con nippli<\/li>\n<li>Bloccaggi centrali delle ruote Borrani a tre foglie<\/li>\n<li>Serbatoio dell'olio e serbatoio del carburante ausiliario in acciaio inox con disposizione dei rivetti prototipale<\/li>\n<li>Frizione esterna con corona dentata di avviamento<\/li>\n<\/ul>\n<\/div>\n<h4>Descrizione del veicolo originale:<\/h4>\n<div>La stagione agonistica 1961 \u00e8 dominata da due piloti Ferrari: l'americano Phil Hill e il tedesco Wolfgang Graf Berghe von Trips, che con i suoi modi modesti conquista i cuori dei suoi connazionali. I due compagni di squadra guidano la Scuderia di vittoria in vittoria.<br \/>\nOltre che alle loro capacit\u00e0 di guida, questo successo fu indubbiamente dovuto alla nuova auto da corsa, sviluppata per la formula da competizione da 1,5 litri in vigore dal 1961. Il suo tratto distintivo pi\u00f9 evidente \u00e8 il muso appuntito con prese d'aria di raffreddamento dalla forma insolita, che le valse ben presto il soprannome di \u201eSharknose\u201c.<br \/>\nLa lotta per il titolo tra Graf Berghe von Trips e Phil Hill si svolge il 10 settembre 1961 a Monza. Il tedesco aveva 33 punti, l'americano 29. Von Trips parte per la prima volta dalla pole position, ma commette un errore e rischia di perdere contatto. Ma non si arrende, supera prima Brabham, poi Clark, tira a sinistra prima della curva ripida e non si accorge che Clark ha lanciato un contrattacco ed \u00e8 gi\u00e0 all'altezza del retrotreno della Ferrari con la sua Lotus. Le auto si scontrano. La Ferrari si ribalta due volte e viene scaraventata contro una recinzione, dietro la quale sono assiepati gli spettatori. Von Trips viene sbalzato fuori dall'abitacolo e muore sul colpo. Con lui muoiono 15 spettatori. \u00c8 uno dei giorni pi\u00f9 bui della storia dell'automobilismo.<br \/>\nPhil Hill vince la gara e diventa il primo americano a diventare Campione del Mondo di Formula 1. La Ferrari vince anche il titolo costruttori.<\/div>\n<p>Numero articolo: M-068<\/p>","protected":false},"excerpt":{"rendered":"<p>M-068 \u2013 2-neuwertig \u2013 290,00 \u20ac<\/p>","protected":false},"featured_media":43805,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[537],"product_cat":[18,63,21],"product_tag":[64,65,66,67],"class_list":["post-134","product","type-product","status-publish","has-post-thumbnail","product_brand-cmc","product_cat-cmc","product_cat-ferrari","product_cat-verfuegbar","product_tag-64","product_tag-cmc-ferrari-156f1","product_tag-hill-monza","product_tag-startnummer-2","pa_automarke-ferrari","pa_decade-1960s","pa_fahrzeugtyp-formel-1","pa_farbe-rot","pa_limitiert-ja","pa_massstab-973","pa_modelmarke-cmc","pa_modeltyp-alles-zum-oeffnen","pa_modeltyp-fertigmodell","pa_status-beim-hersteller-ausverkauft","pa_verfuegbarkeit-nicht-verfuegbar","pa_zustand_modell-2-neuwertig","pa_zustand_verpackung-2-neuwertig","first","outofstock","purchasable","product-type-simple"],"acf":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.modelcars24.de\/it\/wp-json\/wp\/v2\/product\/134","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.modelcars24.de\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.modelcars24.de\/it\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.modelcars24.de\/it\/wp-json\/wp\/v2\/comments?post=134"}],"version-history":[{"count":0,"href":"https:\/\/www.modelcars24.de\/it\/wp-json\/wp\/v2\/product\/134\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.modelcars24.de\/it\/wp-json\/wp\/v2\/media\/43805"}],"wp:attachment":[{"href":"https:\/\/www.modelcars24.de\/it\/wp-json\/wp\/v2\/media?parent=134"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.modelcars24.de\/it\/wp-json\/wp\/v2\/product_brand?post=134"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.modelcars24.de\/it\/wp-json\/wp\/v2\/product_cat?post=134"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.modelcars24.de\/it\/wp-json\/wp\/v2\/product_tag?post=134"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}