{"id":31459,"date":"2024-12-29T23:28:31","date_gmt":"2024-12-29T22:28:31","guid":{"rendered":"http:\/\/www.mondo-legno.com\/?post_type=product&#038;p=31459"},"modified":"2026-03-25T07:26:40","modified_gmt":"2026-03-25T06:26:40","slug":"ixo-mercedes-300-sl-kit-argento-18","status":"publish","type":"product","link":"https:\/\/www.modelcars24.de\/it\/ixo-mercedes-300-sl-silber-bausatz-18\/","title":{"rendered":"IXO Mercedes 300 SL argento kit 1:8 - 1\/8"},"content":{"rendered":"<p>IXO Mercedes 300 SL argento. Modello finito di alta qualit\u00e0 in scala 1:8<\/p>\n<p>La Mercedes 300 SL era l'auto pi\u00f9 veloce del suo tempo. Grazie al suo design ingegnoso e alle porte a farfalla, \u00e8 considerata la prima \u201esupersportiva\u201c al mondo.<\/p>\n<p>La Mercedes 300 SL \u00e8 stata una leggenda dell'automobilismo fin dal primo giorno: Il suo design accattivante, con le spettacolari porte a farfalla, oltre a numerose innovazioni tecniche e a un motore eccezionale, hanno sconvolto anche i piloti pi\u00f9 entusiasti.<\/p>\n<p>Molti fan della Mercedes 300 SL la consideravano la prima \u201esupersportiva\u201c al mondo. Aveva anche il suo prezzo. Secondo Mercedes, ne furono costruiti 1400 esemplari. Ognuno di essi costava l'incredibile cifra di 29.000 marchi tedeschi. Nel 1954, con quella cifra si poteva comprare uno yacht di lusso.<\/p>\n<p>La velocit\u00e0 della 300 SL era senza precedenti, molto pi\u00f9 alta di quella di qualsiasi altra vettura stradale: 240 km\/h, quando la maggior parte delle sue contemporanee raggiungeva solo la met\u00e0 di questa velocit\u00e0.<\/p>\n<p>Ma non erano solo le prestazioni che i fortunati proprietari acquistavano a questo prezzo, perch\u00e9 era soprattutto il suo design a rendere la 300 SL un capolavoro. L'auto era perfetta da ogni punto di vista, coronata da un mix unico di esclusivit\u00e0 e funzionalit\u00e0, il cui elemento pi\u00f9 insolito erano le straordinarie porte a farfalla. Con questo design, la 300 SL divenne la prima auto sportiva al mondo prodotta in serie, prima ancora di Ferrari, Lamborghini e altre.<\/p>\n<p>Dettagli sul modello 1\/8: Su licenza ufficiale Mercedes.<\/p>\n<p>Mercedes-Benz 300 Sl Coup\u00e9 del 1955.<\/p>\n<p>- Lunghezza: 56,5 cm.<\/p>\n<p>- Le porte a farfalla, il cofano e il cofano del bagagliaio possono essere aperti per rivelare un interno dettagliato e realistico.<\/p>\n<p>- L'accensione dei fari avviene tramite un comando sul cruscotto.<\/p>\n<p>- Le luci dei freni si accendono quando si preme il pedale del freno.<\/p>\n<p>- Lo sterzo funziona, le ruote anteriori girano seguendo il movimento del volante.<\/p>\n<p>- Il motore corrisponde a quello del veicolo originale.<\/p>\n<p>Scala 1\/8 - Lunghezza 58 cm - Larghezza 23 cm - Altezza 16 cm - Peso 7,3Kg - Pi\u00f9 di 602 parti di cui 113 in metallo - Funzione di luce -<\/p>\n<p>Dati tecnici:<\/p>\n<p>Scala: 1:8<br \/>\nLunghezza: 56,5 cm<br \/>\nLarghezza: 23 cm<br \/>\nAltezza: 16 cm<br \/>\nPeso: 7,3 kg<br \/>\nOltre 602 parti, di cui 113 in metallo<br \/>\nFunzione fari e luci posteriori<br \/>\nSterzo funzionale<br \/>\nMotore dettagliato<br \/>\nLicenza ufficiale Mercedes-Benz<\/p>\n<p>Numero articolo: IXC.MBC.FK<\/p>","protected":false},"excerpt":{"rendered":"<p>10107 &#8211; 1-brandneu &#8211; anstatt 990,00 jetzt 899,00 \u20ac inkl. 19% Vat<\/p>","protected":false},"featured_media":49097,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[839],"product_cat":[417,272,21],"product_tag":[460,316,263],"class_list":["post-31459","product","type-product","status-publish","has-post-thumbnail","product_brand-ixo","product_cat-ixo","product_cat-mercedes","product_cat-verfuegbar","product_tag-ixo","product_tag-mercedes","product_tag-vorbestellbar","product_shipping_class-sperrgut","pa_automarke-mercedes","pa_decade-1960s","pa_fahrzeugtyp-coupe","pa_limitiert-nein","pa_massstab-1-8","pa_modelmarke-ixo","pa_modeltyp-alles-zum-oeffnen","pa_modeltyp-bausatz","pa_status-beim-hersteller-verfuegbar","pa_verfuegbarkeit-sofort-verfuegbar","pa_zustand_modell-1-brandneu","pa_zustand_verpackung-1-brandneu","first","instock","sale","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.modelcars24.de\/it\/wp-json\/wp\/v2\/product\/31459","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.modelcars24.de\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.modelcars24.de\/it\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.modelcars24.de\/it\/wp-json\/wp\/v2\/comments?post=31459"}],"version-history":[{"count":0,"href":"https:\/\/www.modelcars24.de\/it\/wp-json\/wp\/v2\/product\/31459\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.modelcars24.de\/it\/wp-json\/wp\/v2\/media\/49097"}],"wp:attachment":[{"href":"https:\/\/www.modelcars24.de\/it\/wp-json\/wp\/v2\/media?parent=31459"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.modelcars24.de\/it\/wp-json\/wp\/v2\/product_brand?post=31459"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.modelcars24.de\/it\/wp-json\/wp\/v2\/product_cat?post=31459"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.modelcars24.de\/it\/wp-json\/wp\/v2\/product_tag?post=31459"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}