{"id":70241,"date":"2026-07-15T11:09:45","date_gmt":"2026-07-15T09:09:45","guid":{"rendered":"https:\/\/www.modelcars24.de\/?post_type=product&#038;p=70241"},"modified":"2026-07-15T16:34:26","modified_gmt":"2026-07-15T14:34:26","slug":"autoart-ford-f-150-raptor-supercrew-2019-118-velocity-blue","status":"publish","type":"product","link":"https:\/\/www.modelcars24.de\/ja\/autoart-ford-f-150-raptor-supercrew-2019-118-velocity-blue\/","title":{"rendered":"\u30aa\u30fc\u30c8\u30a2\u30fc\u30c8 \u30d5\u30a9\u30fc\u30c9 F-150 \u30e9\u30d7\u30bf\u30fc \u30b9\u30fc\u30d1\u30fc\u30af\u30eb\u30fc 2019 1:18 \u2013 \u30d9\u30ed\u30b7\u30c6\u30a3\u30d6\u30eb\u30fc"},"content":{"rendered":"<h2>\u30aa\u30fc\u30c8\u30a2\u30fc\u30c8 \u30d5\u30a9\u30fc\u30c9 F-150 \u30e9\u30d7\u30bf\u30fc \u30b9\u30fc\u30d1\u30fc\u30af\u30eb\u30fc 2019 1:18 \u2013 \u30d9\u30ed\u30b7\u30c6\u30a3\u30d6\u30eb\u30fc<\/h2>\n<div class=\"product-intro\">\n<p>Der Ford F-150 Raptor Supercrew des Modelljahres 2019 verk\u00f6rpert eine Kombination aus robustem Nutzwert und hochleistungsf\u00e4higer Gel\u00e4ndetechnik. Als Spitzenmodell der F-Serie wurde der Raptor speziell f\u00fcr anspruchsvolle Offroad-Bedingungen konzipiert und orientiert sich an den W\u00fcstenrennfahrtzeugen der Baja 1000. Angetrieben von einem leistungsstarken 3,5-Liter-EcoBoost-V6-Motor mit Twin-Turbo-Aufladung bietet das Originalfahrzeug neben einer enormen Leistungsentfaltung auch ein hochentwickeltes Fahrwerk mit speziellen FOX-Sto\u00dfd\u00e4mpfern. In der Supercrew-Variante verbindet der Pick-up diese fahrdynamischen Eigenschaften mit einer ger\u00e4umigen Doppelkabine, die hohen Fahrkomfort auch abseits befestigter Stra\u00dfen gew\u00e4hrleistet.<\/p>\n<p>Dieses Miniaturmodell von AUTOart im Ma\u00dfstab 1:18 bildet die markante Formensprache und die technischen Finessen des Ford F-150 Raptor pr\u00e4zise ab. Die Karosserie ist in der originalgetreuen Lackierung <strong>Velocity Blue<\/strong> gehalten, welche die bullige Erscheinung des Fahrzeugs unterstreicht. Im Sinne der gesch\u00e4tzten AUTOart-Fertigungsqualit\u00e4t lassen sich bei dieser Miniatur die Vordert\u00fcren, die hinteren Fondt\u00fcren sowie die Motorhaube und die Ladebordwand \u00f6ffnen. Der Blick in den Motorraum offenbart eine akkurate Nachbildung des V6-Triebwerks \u20ac inklusive zahlreicher Schl\u00e4uche, Leitungen und Abdeckungen. Auch das Interieur ist detailliert nachempfunden und weist feine Texturen auf den Sitzen sowie eine exakte Instrumentierung auf. Lenkbare Vorderr\u00e4der und eine authentische Nachbildung der grobstolligen Offroad-Bereifung samt der fahrzeugspezifischen Felgen runden den hochwertigen Gesamteindruck des Sammlermodells ab.<\/p>\n<\/div>\n<p><strong>Zustand:<\/strong> 1 &#8211; brandneu<br \/>\n<strong>Artikelnummer (SKU):<\/strong>72949<\/p>","protected":false},"excerpt":{"rendered":"<p>AUTOart Ford F-150 Raptor &#8211; 72949 \u2013 1-brandneu \u2013 295\u20ac inkl. 19% Vat<\/p>","protected":false},"featured_media":70220,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[21],"product_tag":[],"class_list":["post-70241","product","type-product","status-publish","has-post-thumbnail","product_cat-verfuegbar","pa_automarke-ford","pa_decade-2010er","pa_fahrzeugtyp-pick-up","pa_farbe-velocity-blue","pa_limitiert-nein","pa_massstab-973","pa_modelmarke-autoart","pa_modeltyp-alles-zum-oeffnen-fertigmodell","pa_verfuegbarkeit-verfuegbar","pa_zustand_modell-1-brandneu","pa_zustand_verpackung-1-brandneu","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.modelcars24.de\/ja\/wp-json\/wp\/v2\/product\/70241","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.modelcars24.de\/ja\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.modelcars24.de\/ja\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.modelcars24.de\/ja\/wp-json\/wp\/v2\/comments?post=70241"}],"version-history":[{"count":1,"href":"https:\/\/www.modelcars24.de\/ja\/wp-json\/wp\/v2\/product\/70241\/revisions"}],"predecessor-version":[{"id":71723,"href":"https:\/\/www.modelcars24.de\/ja\/wp-json\/wp\/v2\/product\/70241\/revisions\/71723"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.modelcars24.de\/ja\/wp-json\/wp\/v2\/media\/70220"}],"wp:attachment":[{"href":"https:\/\/www.modelcars24.de\/ja\/wp-json\/wp\/v2\/media?parent=70241"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.modelcars24.de\/ja\/wp-json\/wp\/v2\/product_brand?post=70241"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.modelcars24.de\/ja\/wp-json\/wp\/v2\/product_cat?post=70241"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.modelcars24.de\/ja\/wp-json\/wp\/v2\/product_tag?post=70241"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}