{"id":83001,"date":"2026-09-01T20:33:02","date_gmt":"2026-09-01T18:33:02","guid":{"rendered":"https:\/\/www.modelcars24.de\/?post_type=product&#038;p=83001"},"modified":"2026-09-02T09:03:49","modified_gmt":"2026-09-02T07:03:49","slug":"bbr-ferrari-12cilindri-manuale-panoramic-roof-brushed-aluminum-118","status":"publish","type":"product","link":"https:\/\/www.modelcars24.de\/ja\/bbr-ferrari-12cilindri-manuale-panoramic-roof-brushed-aluminum-118\/","title":{"rendered":"BBR Ferrari 12Cilindri Manuale Panoramic Roof &#8211; Brushed Aluminum | 1:18"},"content":{"rendered":"<h2>BBR Ferrari 12Cilindri Manuale Panoramic Roof &#8211; Brushed Aluminum | 1:18<\/h2>\n<div class=\"product-intro\">\n<p>Im Juli 2026 pr\u00e4sentiert, bringt diese auf 1.499 Exemplare limitierte Edition das klassische Schaltgetriebe-Erlebnis zur\u00fcck nach Maranello. Mit dem innovativen System &quot;Manuale by-wire&quot; wird die traditionelle mechanische \u00dcbertragung durch eine fortschrittliche elektronische Simulation ersetzt. Dabei sind Schalthebel und Kupplungspedal mit Sensoren verbunden, die das Doppelkupplungsgetriebe pr\u00e4zise steuern. Der Innenraum besticht durch einen Stahlschalthebel und die R\u00fcckkehr der ikonischen, offenen H-Schaltkulisse, welche einen realistischen mechanischen Widerstand sowie das charakteristische akustische Klicken bietet. Erg\u00e4nzt wird dieses authentische Setup durch eine klassische Anordnung mit drei Pedalen.<\/p>\n<p>Diese technische Entwicklung beendet eine 14-j\u00e4hrige Pause seit dem Ende der serienm\u00e4\u00dfigen Schaltgetriebe-Produktion bei Modellen wie dem 599 GTB Fiorano und dem California im Jahr 2012. <strong>Exklusive Ausstattungsmerkmale<\/strong> heben diese Edition vom Standardmodell ab: Ein lasergraviertes seitliches Scudetto aus Metall, geschmiedete F\u00fcnfspeichenfelgen und ein Zierstreifen mit &quot;Manuale&quot;-Schriftzug am vorderen Radhaus zitieren die historische Formensprache der legend\u00e4ren 365 GTB4.<\/p>\n<p>Das Sammlerst\u00fcck wird inklusive einer hochwertigen Pr\u00e4sentationsvitrine geliefert.<\/p>\n<\/div>\n<p>\n<strong>\u72b6\u614b<\/strong> 1 \u2013 \u771f\u65b0\u3057\u3044<br \/>\n<strong>\u5546\u54c1\u756a\u53f7\uff08SKU\uff09\uff1a<\/strong> P18286B<\/p>","protected":false},"excerpt":{"rendered":"<p>BBR Ferrari 12Cilindri &#8211; P18286B \u2013 preorder \u2013 466 inkl. 19% Vat<\/p>","protected":false},"featured_media":82999,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[262],"product_tag":[],"class_list":["post-83001","product","type-product","status-publish","has-post-thumbnail","product_cat-vorbestellbar","pa_automarke-ferrari","pa_decade-2020s","pa_fahrzeugtyp-supersportwagen","pa_farbe-alluminio-spazzolato","pa_limitiert-ja","pa_massstab-973","pa_modelmarke-bbr","pa_modeltyp-geschlossenfertigmodell","pa_verfuegbarkeit-vorbestellbar","pa_zustand_modell-1-brandneu","pa_zustand_verpackung-1-brandneu","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.modelcars24.de\/ja\/wp-json\/wp\/v2\/product\/83001","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.modelcars24.de\/ja\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.modelcars24.de\/ja\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.modelcars24.de\/ja\/wp-json\/wp\/v2\/comments?post=83001"}],"version-history":[{"count":1,"href":"https:\/\/www.modelcars24.de\/ja\/wp-json\/wp\/v2\/product\/83001\/revisions"}],"predecessor-version":[{"id":83030,"href":"https:\/\/www.modelcars24.de\/ja\/wp-json\/wp\/v2\/product\/83001\/revisions\/83030"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.modelcars24.de\/ja\/wp-json\/wp\/v2\/media\/82999"}],"wp:attachment":[{"href":"https:\/\/www.modelcars24.de\/ja\/wp-json\/wp\/v2\/media?parent=83001"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.modelcars24.de\/ja\/wp-json\/wp\/v2\/product_brand?post=83001"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.modelcars24.de\/ja\/wp-json\/wp\/v2\/product_cat?post=83001"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.modelcars24.de\/ja\/wp-json\/wp\/v2\/product_tag?post=83001"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}